{"id":488,"date":"2011-03-15T10:23:02","date_gmt":"2011-03-15T10:23:02","guid":{"rendered":"https:\/\/www.mondilocali.it\/?page_id=488"},"modified":"2011-03-15T10:23:02","modified_gmt":"2011-03-15T10:23:02","slug":"ecomuseo-del-paesaggio-orvietano","status":"publish","type":"page","link":"https:\/\/www.ecomusei.eu\/mondilocali\/ecomusei\/ecomuseo-del-paesaggio-orvietano\/","title":{"rendered":"Ecomuseo del paesaggio Orvietano"},"content":{"rendered":"<p><strong>Localit\u00e0<\/strong>:<br \/>\nComuni di Fabro, Ficulle, Monteleone d&#8217;Orvieto, Montegabbione, Parrano e San Venanzo, situati amministrativamente al margine nord-occidentale della Provincia di Terni.<\/p>\n<p><strong>Referente<\/strong>: &#8212;<\/p>\n<p><strong>Presentazione<\/strong>:<\/p>\n<p>L&#8217;Ecomuseo \u00e8 istituzione culturale volta a rappresentare e valorizzare i caratteri, il paesaggio, la memoria e l&#8217;identit\u00e0 di un determinato territorio e della popolazione che vi \u00e8 storicamente insediata, anche al fine di orientarne lo sviluppo futuro. L&#8217;obiettivo \u00e8 rendere le comunit\u00e0 locali consapevoli della propria identit\u00e0, attraverso un processo che consiste nell&#8217;individuazione delle componenti del patrimonio locale, in uno studio meticoloso dei saperi tradizionali diffusi e nella trasmissione di beni e conoscenze.<strong> <\/strong>L\u2019Ecomuseo del paesaggio Orvietano comprende 8 comuni, con una superficie complessiva pari a 380 Kmq e una popolazione di circa 10.000 abitanti.<strong><\/strong><\/p>\n<p><strong>Anno di fondazione<\/strong>: &#8212;<\/p>\n<p><strong>Ente titolare<\/strong>:<br \/>\nProvincia di Terni<\/p>\n<p><strong>Sede operativa<\/strong>:<br \/>\nc\/o Provincia di Terni &#8211; Dott.ssa Ilaria Venturi \u00a00744.483321<\/p>\n<p><a href=\"http:\/\/cms.provincia.terni.it\/on-line\/Home\/Ilterritorio\/Ecomuseo.html\">Sito internet<\/a> &#8211; <a href=\"mailto:edilizia@provincia.terni.it\">e-mail<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Localit\u00e0: Comuni di Fabro, Ficulle, Monteleone d&#8217;Orvieto, Montegabbione, Parrano e San Venanzo, situati amministrativamente al margine nord-occidentale della Provincia di Terni. Referente: &#8212; Presentazione: L&#8217;Ecomuseo \u00e8 istituzione culturale volta a rappresentare e valorizzare i caratteri, il paesaggio, la memoria e l&#8217;identit\u00e0 di un determinato territorio e della popolazione che vi \u00e8 storicamente insediata, anche al&#8230;<\/p>\n","protected":false},"author":2,"featured_media":0,"parent":23,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-488","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.ecomusei.eu\/mondilocali\/wp-json\/wp\/v2\/pages\/488","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.ecomusei.eu\/mondilocali\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.ecomusei.eu\/mondilocali\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.ecomusei.eu\/mondilocali\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.ecomusei.eu\/mondilocali\/wp-json\/wp\/v2\/comments?post=488"}],"version-history":[{"count":0,"href":"https:\/\/www.ecomusei.eu\/mondilocali\/wp-json\/wp\/v2\/pages\/488\/revisions"}],"up":[{"embeddable":true,"href":"https:\/\/www.ecomusei.eu\/mondilocali\/wp-json\/wp\/v2\/pages\/23"}],"wp:attachment":[{"href":"https:\/\/www.ecomusei.eu\/mondilocali\/wp-json\/wp\/v2\/media?parent=488"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}